{"id":18154,"date":"2020-11-03T10:01:00","date_gmt":"2020-11-03T09:01:00","guid":{"rendered":"https:\/\/www.ringier.com\/?p=18154"},"modified":"2025-07-18T10:09:05","modified_gmt":"2025-07-18T08:09:05","slug":"le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag","status":"publish","type":"post","link":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/","title":{"rendered":"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG"},"content":{"rendered":"\n<p>Aufgrund strategischer \u00dcberlegungen ver\u00e4ussert Ringier Axel Springer Schweiz AG die Westschweizer Tageszeitung&nbsp;<em>Le Temps<\/em>&nbsp;an die Stiftung Aventinus, deren Ziel die Unterst\u00fctzung von unabh\u00e4ngigem und vielf\u00e4ltigem Qualit\u00e4tsjournalismus ist. Ausschlaggebend f\u00fcr den Entscheid des Verlags sind mangelnde Synergien mit seinem publizistischen Portfolio, welches zum gr\u00f6ssten Teil aus Zeitschriften besteht. Langfristig sichert der Verkauf an Aventinus die Zukunft des Titels mitsamt seiner \u00fcber hundert Arbeitspl\u00e4tze. Die Stiftung beabsichtigt,&nbsp;<em>Le Temps<\/em>&nbsp;als unabh\u00e4ngige Qualit\u00e4tszeitung weiterzuf\u00fchren und die gesamte Redaktion zu \u00fcbernehmen. Der bisherige Chefredaktor St\u00e9phane Benoit-Godet wechselt in derselben Funktion zum verlagseigenen Magazin&nbsp;<em>L\u2019illustr\u00e9<\/em>.<\/p>\n\n\n\n<p><strong>Vorteile des Stiftungsmodells<\/strong><\/p>\n\n\n\n<p>\u00ab<em>Le Temps<\/em>&nbsp;ist eine hochwertige Tageszeitung und \u00fcber die Romandie hinaus von zentraler Bedeutung\u00bb, erkl\u00e4rt Alexander Theobald, CEO von Ringier Axel Springer Schweiz. \u00abSo, wie wir als Verlagshaus aufgestellt sind, k\u00f6nnen wir ihr jedoch nicht die sichere Zukunft bieten, die sie aufgrund ihrer Stellung verdient.\u00bb Als Westschweizer Tageszeitung konnte&nbsp;<em>Le Temps<\/em>&nbsp;nur bedingt von Synergien innerhalb des Portfolios von Ringier Axel Springer Schweiz profitieren.<\/p>\n\n\n\n<p>Das Medienunternehmen Ringier Axel Springer Schweiz ist zum Schluss gekommen, dass die Weiterf\u00fchrung durch das Engagement einer renommierten Stiftung langfristig erfolgversprechender ist. \u00abDie \u00dcbernahme der Tageszeitung&nbsp;<em>Le Temps<\/em>&nbsp;durch Aventinus ist eine gute Nachricht\u00bb, so Alexander Theobald. \u00abDas Stiftungsmodell ist f\u00fcr die Schweizer Medienlandschaft neu \u2013 einen \u00e4hnlichen Weg sind bereits Qualit\u00e4tszeitungen in Frankreich oder Grossbritannien gegangen. Mit Aventinus ist der langfristige Fortbestand des Qualit\u00e4tsjournalismus, f\u00fcr den&nbsp;<em>Le Temps<\/em>&nbsp;steht, in der Romandie gew\u00e4hrleistet. Die Stiftung ist finanziell unabh\u00e4ngig und in der Westschweiz hervorragend vernetzt \u2013 diese L\u00f6sung stellt&nbsp;<em>Le Temps<\/em>&nbsp;auf ein solides Fundament. Im aktuellen Marktumfeld ist dies f\u00fcr eine Publikation wie&nbsp;<em>Le Temps<\/em>&nbsp;eine optimale Situation.\u00bb<\/p>\n\n\n\n<p><strong>Langfristige und unabh\u00e4ngige Zukunft<\/strong><\/p>\n\n\n\n<p>\u00ab<em>Le Temps<\/em>&nbsp;ist eine wichtige Stimme der Romandie und wir danken Ringier Axel Springer Schweiz f\u00fcr das bisherige Engagement\u00bb, sagt Fran\u00e7ois Longchamp, Pr\u00e4sident der Stiftung Aventinus und ehemaliger Pr\u00e4sident des Genfer Staatsrats. \u00abWir sind stolz darauf, den bedeutenden Titel weiterf\u00fchren zu k\u00f6nnen und ihre Redaktion bald in Genf willkommen zu heissen. Unsere Mission ist es, qualitativ hochstehende, autonome und vielf\u00e4ltige Medien in der Westschweiz zu unterst\u00fctzen und zu f\u00f6rdern. Gerade in einer Zeit, in der in der Medienwelt eine turbulente Phase durchl\u00e4uft, k\u00f6nnen wir das Redaktionsteam von&nbsp;<em>Le Temps<\/em>&nbsp;dabei unterst\u00fctzen, dem Titel wirtschaftlich eine langfristige Zukunft zu sichern.\u00bb<\/p>\n\n\n\n<p>Die Stiftung Aventinus wurde im Oktober 2019 dank der Unterst\u00fctzung mehrerer Stiftungen gegr\u00fcndet \u2013 darunter die Leenaards Stiftung, die Fondation Jan Michalski pour l\u2019\u00e9criture et la litt\u00e9rature und die Hans Wilsdorf Stiftung. Mehrere private M\u00e4zene haben ebenfalls wichtige Unterst\u00fctzung geleistet. Die Stiftung Aventinus und ihre Gr\u00fcnder legen grossen Wert auf Unabh\u00e4ngigkeit. Aus diesem Grund verzichten die Spenderstiftungen auf eine Vertretung im Aventinus-Vorstand; zudem werden im Verwaltungsrat von&nbsp;<em>Le Temps<\/em>&nbsp;keine Mitglieder von Aventinus oder deren Spenderstiftungen Einsitz nehmen.<\/p>\n\n\n\n<p><strong>Neuaufstellung<\/strong><\/p>\n\n\n\n<p>Um den Erwerb von&nbsp;<em>Le Temps<\/em>&nbsp;zu erm\u00f6glichen, hat die Stiftung Aventinus vor einigen Monaten eine Arbeitsgruppe eingerichtet, die sich aus anerkannten Experten f\u00fcr Kommunikation und Medien zusammensetzt. Dazu geh\u00f6ren Eric Hoesli, damals der erste Chefredaktor von&nbsp;<em>Le Temps<\/em>, sowie Ir\u00e8ne Challand, Abir Oreibi, Tib\u00e8re Adler, Yves Daccord und Pascal Meyer. Diese Gruppe hat nun die Aufgabe, den operativen \u00dcbergang zu gew\u00e4hrleisten, die neuen redaktionellen, finanziellen und administrativen Leiter des Titels zu ernennen sowie die strategische Ausrichtung f\u00fcr die kommenden Jahre festzulegen.<\/p>\n\n\n\n<p>Bis zum Abschluss der Transaktion wird Aventinus den neuen Verwaltungsrat von&nbsp;<em>Le Temps<\/em>&nbsp;zusammenstellen, der unter dem Vorsitz von Eric Hoesli aus f\u00fcnf bis sechs unabh\u00e4ngigen Mitgliedern bestehen wird. Dar\u00fcber hinaus hat die Stiftung im vergangenen Dezember den Erwerb einer Minderheitsbeteiligung von Heidi Media SA bekanntgegeben und soeben Gespr\u00e4che zur \u00dcbernahme dieses Newsportals aufgenommen. So sollen zus\u00e4tzliche Synergien f\u00fcr&nbsp;<em>Le Temps<\/em>&nbsp;entstehen und die Stellung des Titels weiter st\u00e4rken.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-small-font-size\">Corporate&nbsp;Communications<br>+41 44 259 64 44<br><a href=\"mailto:media@ringier.ch\" target=\"_blank\" rel=\"noreferrer noopener\">media@ringier.ch<\/a> <br><a href=\"https:\/\/www.ringier.com\/de\/\">www.ringier.co<\/a><a href=\"https:\/\/www.ringier.com\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">m<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-left has-small-font-size\">Ringier<br>Dufourstrasse 23<br>8008 Z\u00fcrich<br>Schweiz<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ringier Axel Springer Schweiz AG passt ihr Portfolio strategisch an und verkauft Le Temps SA und damit die Tageszeitung Le Temps per 1. Januar 2021 an die Stiftung Aventinus mit Sitz in Carouge (GE). Der Verlag fokussiert k\u00fcnftig auf seine publizistischen Kernprodukte. Durch die \u00dcbernahme von Le Temps durch Aventinus wird der langfristige Fortbestand des Titels sowie seiner Arbeitspl\u00e4tze sichergestellt. Die Redaktion zieht von Lausanne nach Genf.<\/p>\n","protected":false},"author":23,"featured_media":18155,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[371,361],"tags":[],"class_list":["post-18154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-de","category-ringier-medien-schweiz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG - Ringier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG\" \/>\n<meta property=\"og:description\" content=\"Die Ringier Axel Springer Schweiz AG passt ihr Portfolio strategisch an und verkauft Le Temps SA und damit die Tageszeitung Le Temps per 1. Januar 2021 an die Stiftung Aventinus mit Sitz in Carouge (GE). Der Verlag fokussiert k\u00fcnftig auf seine publizistischen Kernprodukte. Durch die \u00dcbernahme von Le Temps durch Aventinus wird der langfristige Fortbestand des Titels sowie seiner Arbeitspl\u00e4tze sichergestellt. Die Redaktion zieht von Lausanne nach Genf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/\" \/>\n<meta property=\"og:site_name\" content=\"Ringier\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ringierag\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-03T09:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T08:09:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ringier.com\/wp-content\/uploads\/2024\/01\/logo_le_temps_2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ringier Corporate Communications\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ringier_ag\" \/>\n<meta name=\"twitter:site\" content=\"@ringier_ag\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ringier Corporate Communications\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/\"},\"author\":{\"name\":\"Ringier Corporate Communications\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#\\\/schema\\\/person\\\/4cf76a308dc4b2bb5121bd1e7b752e52\"},\"headline\":\"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG\",\"datePublished\":\"2020-11-03T09:01:00+00:00\",\"dateModified\":\"2025-07-18T08:09:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/\"},\"wordCount\":711,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ringier.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_le_temps_2020.jpg\",\"articleSection\":[\"Media\",\"Ringier Medien Schweiz\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/\",\"url\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/\",\"name\":\"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG - Ringier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ringier.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_le_temps_2020.jpg\",\"datePublished\":\"2020-11-03T09:01:00+00:00\",\"dateModified\":\"2025-07-18T08:09:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ringier.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_le_temps_2020.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ringier.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_le_temps_2020.jpg\",\"width\":2000,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/\",\"name\":\"Ringier\",\"description\":\"We inform. We entertain. We connect\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#organization\",\"name\":\"Ringier\",\"url\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ringier.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ringier_logo_2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ringier.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ringier_logo_2.jpg\",\"width\":750,\"height\":550,\"caption\":\"Ringier\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ringierag\\\/\",\"https:\\\/\\\/x.com\\\/ringier_ag\",\"https:\\\/\\\/www.instagram.com\\\/ringier_ag\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ringier\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/RingierComm\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Ringier\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Ringier\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Ringier\",\"https:\\\/\\\/www.crunchbase.com\\\/organization\\\/ringier-ag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ringier.com\\\/de\\\/#\\\/schema\\\/person\\\/4cf76a308dc4b2bb5121bd1e7b752e52\",\"name\":\"Ringier Corporate Communications\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9391e20481368d5df4fe3e1e476c13b27786347489822ec1ed07e532bb41f587?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9391e20481368d5df4fe3e1e476c13b27786347489822ec1ed07e532bb41f587?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9391e20481368d5df4fe3e1e476c13b27786347489822ec1ed07e532bb41f587?s=96&d=mm&r=g\",\"caption\":\"Ringier Corporate Communications\"},\"sameAs\":[\"https:\\\/\\\/www.ringier.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG - Ringier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/","og_locale":"de_DE","og_type":"article","og_title":"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG","og_description":"Die Ringier Axel Springer Schweiz AG passt ihr Portfolio strategisch an und verkauft Le Temps SA und damit die Tageszeitung Le Temps per 1. Januar 2021 an die Stiftung Aventinus mit Sitz in Carouge (GE). Der Verlag fokussiert k\u00fcnftig auf seine publizistischen Kernprodukte. Durch die \u00dcbernahme von Le Temps durch Aventinus wird der langfristige Fortbestand des Titels sowie seiner Arbeitspl\u00e4tze sichergestellt. Die Redaktion zieht von Lausanne nach Genf.","og_url":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/","og_site_name":"Ringier","article_publisher":"https:\/\/www.facebook.com\/ringierag\/","article_published_time":"2020-11-03T09:01:00+00:00","article_modified_time":"2025-07-18T08:09:05+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/www.ringier.com\/wp-content\/uploads\/2024\/01\/logo_le_temps_2020.jpg","type":"image\/jpeg"}],"author":"Ringier Corporate Communications","twitter_card":"summary_large_image","twitter_creator":"@ringier_ag","twitter_site":"@ringier_ag","twitter_misc":{"Verfasst von":"Ringier Corporate Communications","Gesch\u00e4tzte Lesezeit":"4 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/#article","isPartOf":{"@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/"},"author":{"name":"Ringier Corporate Communications","@id":"https:\/\/www.ringier.com\/de\/#\/schema\/person\/4cf76a308dc4b2bb5121bd1e7b752e52"},"headline":"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG","datePublished":"2020-11-03T09:01:00+00:00","dateModified":"2025-07-18T08:09:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/"},"wordCount":711,"publisher":{"@id":"https:\/\/www.ringier.com\/de\/#organization"},"image":{"@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ringier.com\/wp-content\/uploads\/2024\/01\/logo_le_temps_2020.jpg","articleSection":["Media","Ringier Medien Schweiz"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/","url":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/","name":"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG - Ringier","isPartOf":{"@id":"https:\/\/www.ringier.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/#primaryimage"},"image":{"@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ringier.com\/wp-content\/uploads\/2024\/01\/logo_le_temps_2020.jpg","datePublished":"2020-11-03T09:01:00+00:00","dateModified":"2025-07-18T08:09:05+00:00","breadcrumb":{"@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/#primaryimage","url":"https:\/\/www.ringier.com\/wp-content\/uploads\/2024\/01\/logo_le_temps_2020.jpg","contentUrl":"https:\/\/www.ringier.com\/wp-content\/uploads\/2024\/01\/logo_le_temps_2020.jpg","width":2000,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/www.ringier.com\/de\/le-temps-westschweizer-stiftung-aventinus-uebernimmt-le-temps-sa-von-ringier-axel-springer-schweiz-ag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ringier.com\/de\/"},{"@type":"ListItem","position":2,"name":"Le Temps: Westschweizer Stiftung Aventinus \u00fcbernimmt Le Temps SA von Ringier Axel Springer Schweiz AG"}]},{"@type":"WebSite","@id":"https:\/\/www.ringier.com\/de\/#website","url":"https:\/\/www.ringier.com\/de\/","name":"Ringier","description":"We inform. We entertain. We connect","publisher":{"@id":"https:\/\/www.ringier.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ringier.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.ringier.com\/de\/#organization","name":"Ringier","url":"https:\/\/www.ringier.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.ringier.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.ringier.com\/wp-content\/uploads\/2021\/10\/ringier_logo_2.jpg","contentUrl":"https:\/\/www.ringier.com\/wp-content\/uploads\/2021\/10\/ringier_logo_2.jpg","width":750,"height":550,"caption":"Ringier"},"image":{"@id":"https:\/\/www.ringier.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ringierag\/","https:\/\/x.com\/ringier_ag","https:\/\/www.instagram.com\/ringier_ag\/","https:\/\/www.linkedin.com\/company\/ringier\/","https:\/\/www.youtube.com\/user\/RingierComm","https:\/\/en.wikipedia.org\/wiki\/Ringier","https:\/\/de.wikipedia.org\/wiki\/Ringier","https:\/\/fr.wikipedia.org\/wiki\/Ringier","https:\/\/www.crunchbase.com\/organization\/ringier-ag"]},{"@type":"Person","@id":"https:\/\/www.ringier.com\/de\/#\/schema\/person\/4cf76a308dc4b2bb5121bd1e7b752e52","name":"Ringier Corporate Communications","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/9391e20481368d5df4fe3e1e476c13b27786347489822ec1ed07e532bb41f587?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9391e20481368d5df4fe3e1e476c13b27786347489822ec1ed07e532bb41f587?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9391e20481368d5df4fe3e1e476c13b27786347489822ec1ed07e532bb41f587?s=96&d=mm&r=g","caption":"Ringier Corporate Communications"},"sameAs":["https:\/\/www.ringier.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/posts\/18154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/comments?post=18154"}],"version-history":[{"count":0,"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/posts\/18154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/media\/18155"}],"wp:attachment":[{"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/media?parent=18154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/categories?post=18154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ringier.com\/de\/wp-json\/wp\/v2\/tags?post=18154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}